{"id":244,"date":"2009-03-20T10:40:40","date_gmt":"2009-03-20T09:40:40","guid":{"rendered":"http:\/\/www.grenzsteintrophy.de\/?p=244"},"modified":"2012-12-15T20:02:56","modified_gmt":"2012-12-15T18:02:56","slug":"wer-ohne-rad-starten-will-fur-den-haben-wir-eine-empfehlung","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2009\/03\/wer-ohne-rad-starten-will-fur-den-haben-wir-eine-empfehlung\/","title":{"rendered":"Wer ohne Rad starten will, f\u00fcr den haben wir eine Empfehlung"},"content":{"rendered":"<p>&#8230; bereits im Mai laufen einige &#8220;Grenzsportler&#8221; 1.100 Kilometer entlang der Deutsch-Deutschen-Grenze als Staffellauf&#8230; sicher kein Spaziergang, aber eine tolle Sache. Hier geht es zur <a href=\"http:\/\/www.grenzenloslaufen2009.de\/\" target=\"_blank\">Internetseite <\/a>von Peter und seinen Sportsfreunden.<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8230; bereits im Mai laufen einige &#8220;Grenzsportler&#8221; 1.100 Kilometer entlang der Deutsch-Deutschen-Grenze als Staffellauf&#8230; sicher kein Spaziergang, aber eine tolle Sache. Hier geht es zur Internetseite von Peter und seinen Sportsfreunden.<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[61],"tags":[87],"class_list":["post-244","post","type-post","status-publish","format-standard","hentry","category-grenzsteintrophy","tag-gst-09"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-3W","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=244"}],"version-history":[{"count":0,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/244\/revisions"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}