{"id":2564,"date":"2011-06-19T07:49:08","date_gmt":"2011-06-19T05:49:08","guid":{"rendered":"http:\/\/www.grenzsteintrophy.de\/?p=2564"},"modified":"2012-12-15T20:58:52","modified_gmt":"2012-12-15T18:58:52","slug":"carsten-r-19-06-11-0749","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2011\/06\/carsten-r-19-06-11-0749\/","title":{"rendered":"Carsten R. &#8211; 19.06.11 &#8211; 07:49"},"content":{"rendered":"<p><object style=\"height: 349px; width: 425px\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/avW2NCI68ig?version=3\"><param name=\"allowFullScreen\" value=\"true\"><param name=\"allowScriptAccess\" value=\"always\"><\/object><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[61,83],"tags":[93],"class_list":["post-2564","post","type-post","status-publish","format-standard","hentry","category-grenzsteintrophy","category-gst-doku","tag-gst-11"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-Fm","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/2564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=2564"}],"version-history":[{"count":0,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/2564\/revisions"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=2564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=2564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=2564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}