{"id":2667,"date":"2011-06-21T22:40:17","date_gmt":"2011-06-21T20:40:17","guid":{"rendered":"http:\/\/www.grenzsteintrophy.de\/?p=2667"},"modified":"2012-12-15T20:58:11","modified_gmt":"2012-12-15T18:58:11","slug":"gunter-b-21-06-11-2240","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2011\/06\/gunter-b-21-06-11-2240\/","title":{"rendered":"G\u00fcnter B. &#8211; 21.06.11 &#8211; 22:40"},"content":{"rendered":"<p><object style=\"height: 349px; width: 425px\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/AofdwEWIADQ?version=3\"><param name=\"allowFullScreen\" value=\"true\"><param name=\"allowScriptAccess\" value=\"always\"><\/object><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[61,83],"tags":[93],"class_list":["post-2667","post","type-post","status-publish","format-standard","hentry","category-grenzsteintrophy","category-gst-doku","tag-gst-11"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-H1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/2667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=2667"}],"version-history":[{"count":0,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/2667\/revisions"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=2667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=2667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=2667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}