{"id":3186,"date":"2011-11-23T18:37:15","date_gmt":"2011-11-23T16:37:15","guid":{"rendered":"http:\/\/www.grenzsteintrophy.de\/?p=3186"},"modified":"2012-12-15T21:43:05","modified_gmt":"2012-12-15T19:43:05","slug":"mitfahrer-2012-jan-r","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2011\/11\/mitfahrer-2012-jan-r\/","title":{"rendered":"Mitfahrer 2012: Jan R."},"content":{"rendered":"<p>Hallo GST-Freunde,<\/p>\n<p>bin &uuml;ber die BIKE auf das GST-Event aufmerksam geworden. Ich wu&szlig;te von Anfang an, da&szlig; dies etwas f&uuml;r mich ist. Seit Januar reifte der Gedanke an einer Teilnahme. &nbsp;Mittlerweile habe ich auch die gr&ouml;bsten Hindernisse aus dem Weg ger&auml;umt (Verst&auml;ndnis\/Akzeptanz der Ehefrau ;-)&nbsp; und die Urlaubsplanung). Mental bin ich bereit, physisch bin ich dran &hellip; .<br \/>War letztes Wochenende auf einer Spritztour an der alten Grenze im Bereich Sch&ouml;ningen-Helmstedt. Da ich in Magdeburg wohne, konnte ich die Hin- und R&uuml;ckfahrt auch gleich mit dem Bike bew&auml;ltigen. In H&ouml;tensleben traf mich fast der Schlag, denn da sind ja Teile der alten Befestigungsanlagen fein s&auml;uberlich restauriert erhalten. Das hat den endg&uuml;ltigen Ausschlag gegeben. F&uuml;hlte mich 25 Jahre zur&uuml;ckversetzt, denn in dieser Zeit war ich in diesem Wahnsinn als 19-j&auml;hriger Wehrdienstleistender mit eingebunden gewesen. Oben in einer Grenzkompanie bei L&uuml;beck-Priwall. Ist jetzt ja alles Geschichte. &nbsp;Und auf diesem ja doch geschichtstr&auml;chtigen Pfad m&ouml;chte ich mich im Zuge der GST noch einmal begeben. Verstehe das auch so als Selbstfindungstrip, mal ganz abgesehen von den k&ouml;rperlichen Belastungen. Die Grenzsteintrophy sehe ich f&uuml;r mich als Jacobsweg der Biker.<\/p>\n<p>Kurz und gut:&nbsp;ICH BIN DABEI.<\/p>\n<p>Bitte nehmt mich mit in den Verteiler, so da&szlig; ich auf dem laufenden bleibe.<\/p>\n<p>Gr&uuml;&szlig;e aus Magdeburg<\/p>\n<p>Jan<\/p>","protected":false},"excerpt":{"rendered":"<p>Hallo GST-Freunde, bin &uuml;ber die BIKE auf das GST-Event aufmerksam geworden. Ich wu&szlig;te von Anfang an, da&szlig; dies etwas f&uuml;r mich ist. Seit Januar reifte der Gedanke an einer Teilnahme. &nbsp;Mittlerweile habe ich auch die&#8230; <\/p>\n<p class=\"more\"><a class=\"more-link\" href=\"https:\/\/grenzsteintrophy.de\/en\/2011\/11\/mitfahrer-2012-jan-r\/\">Read More<\/a><\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[61,84],"tags":[86],"class_list":["post-3186","post","type-post","status-publish","format-standard","hentry","category-grenzsteintrophy","category-gst-loi","tag-gst-12"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-Po","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=3186"}],"version-history":[{"count":0,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3186\/revisions"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=3186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=3186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=3186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}