{"id":3294,"date":"2012-01-30T14:10:54","date_gmt":"2012-01-30T12:10:54","guid":{"rendered":"http:\/\/www.grenzsteintrophy.de\/?p=3294"},"modified":"2012-12-15T21:44:02","modified_gmt":"2012-12-15T19:44:02","slug":"mitfahrer-2012-holger-e","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2012\/01\/mitfahrer-2012-holger-e\/","title":{"rendered":"Mitfahrer 2012: Holger E."},"content":{"rendered":"<p>Na, da fahre ich letztens mit dem <a href=\"http:\/\/www.overnighter.de\/?p%3D3117\" target=\"_blank\">Holger<\/a> (und hier nochmal der <a href=\"http:\/\/www.overnighter.de\/?p%3D3093\" target=\"_blank\">Holger<\/a>) sonntagmorgens Rennrad und er beschwert sich bitterlich, dass er noch nicht &uuml;ber den GST-Ticker als Mitfahrer gerauscht ist &#8230; so sei es also nun:<\/p>\n<p>Auch der Holger rollt mit uns am 16.06.2012 am Priwall los!<\/p>","protected":false},"excerpt":{"rendered":"<p>Na, da fahre ich letztens mit dem Holger (und hier nochmal der Holger) sonntagmorgens Rennrad und er beschwert sich bitterlich, dass er noch nicht &uuml;ber den GST-Ticker als Mitfahrer gerauscht ist &#8230; so sei es&#8230; <\/p>\n<p class=\"more\"><a class=\"more-link\" href=\"https:\/\/grenzsteintrophy.de\/en\/2012\/01\/mitfahrer-2012-holger-e\/\">Read More<\/a><\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[61,84],"tags":[86],"class_list":["post-3294","post","type-post","status-publish","format-standard","hentry","category-grenzsteintrophy","category-gst-loi","tag-gst-12"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-R8","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=3294"}],"version-history":[{"count":0,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3294\/revisions"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=3294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=3294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=3294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}