{"id":3320,"date":"2012-02-20T19:42:50","date_gmt":"2012-02-20T17:42:50","guid":{"rendered":"http:\/\/www.grenzsteintrophy.de\/?p=3320"},"modified":"2012-12-15T21:54:09","modified_gmt":"2012-12-15T19:54:09","slug":"henris-grenztour-in-der-trekkingbike","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2012\/02\/henris-grenztour-in-der-trekkingbike\/","title":{"rendered":"Henris Grenztour in der Trekkingbike"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div>\n<p>Der <a href=\"http:\/\/www.overnighter.de\/?s%3Dlesewitz\" target=\"_blank\">Henri<\/a> von der <a href=\"http:\/\/www.bike-magazin.de\/\" target=\"_blank\">Bike<\/a>&nbsp;hat seine coole Grenztour in der aktuellen <a href=\"http:\/\/www.bike-magazin.de\/\">Trekkingbike<\/a> ver&ouml;ffentlicht: Seite 94 bis 98<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.veloarchiv.de\/f9603n\/pn2\/large\/DSCN7326.JPG?1329754926\" alt=\"\" \/><\/p>\n<p>Das coole Foto hier gibt es auch in der&nbsp;<a href=\"http:\/\/issuu.com\/trekkingbike\/docs\/0212_leseprobe\/1\" target=\"_blank\">Leseprobe<\/a>&nbsp;zu sehen. Leider hat es nicht f&uuml;r einen Hinweis auf die GST gereicht. Oder er ist aus Platzgr&uuml;nden herausgeflogen &#8211; wir kennen das &#8230;<\/p>\n<p>Mit Fr&uuml;hlingsputz und Gep&auml;cktr&auml;gertest lohnt die aktuelle Ausgabe auch f&uuml;r uns GSTler. <a href=\"https:\/\/www.delius-klasing.de\/abonnement-service\/auswahl\/TREKKINGBIKE\/19174.html\" target=\"_blank\">Hier kaufen!<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Der Henri von der Bike&nbsp;hat seine coole Grenztour in der aktuellen Trekkingbike ver&ouml;ffentlicht: Seite 94 bis 98 Das coole Foto hier gibt es auch in der&nbsp;Leseprobe&nbsp;zu sehen. Leider hat es nicht f&uuml;r einen Hinweis&#8230; <\/p>\n<p class=\"more\"><a class=\"more-link\" href=\"https:\/\/grenzsteintrophy.de\/en\/2012\/02\/henris-grenztour-in-der-trekkingbike\/\">Read More<\/a><\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[61,95],"tags":[],"class_list":["post-3320","post","type-post","status-publish","format-standard","hentry","category-grenzsteintrophy","category-gst-media"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-Ry","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=3320"}],"version-history":[{"count":0,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3320\/revisions"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=3320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=3320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=3320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}