{"id":3394,"date":"2012-05-30T09:56:41","date_gmt":"2012-05-30T07:56:41","guid":{"rendered":"http:\/\/www.grenzsteintrophy.de\/?p=3394"},"modified":"2012-12-15T21:44:02","modified_gmt":"2012-12-15T19:44:02","slug":"mitfahrer-2012-simon-g","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2012\/05\/mitfahrer-2012-simon-g\/","title":{"rendered":"Mitfahrer 2012: Simon G."},"content":{"rendered":"<blockquote>\n<p>Hallo GST,<br \/>&nbsp;<br \/>ich bin Simon aus S&uuml;ddeutschland und werde am 16.06. auch am Start sein.<br \/>Bitte maile mir alle wichtigen Infos zu. (Treffpunkt, Track etc.) Danke!!<br \/>&nbsp;<br \/>Gru&szlig;<br \/>&nbsp;<br \/>Simon<br \/>&nbsp;<br \/>PS: Muss eigentlich ein Spot benutzt werden?&nbsp;<\/p>\n<\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Hallo GST,&nbsp;ich bin Simon aus S&uuml;ddeutschland und werde am 16.06. auch am Start sein.Bitte maile mir alle wichtigen Infos zu. (Treffpunkt, Track etc.) Danke!!&nbsp;Gru&szlig;&nbsp;Simon&nbsp;PS: Muss eigentlich ein Spot benutzt werden?&nbsp;<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[61,84],"tags":[86],"class_list":["post-3394","post","type-post","status-publish","format-standard","hentry","category-grenzsteintrophy","category-gst-loi","tag-gst-12"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-SK","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=3394"}],"version-history":[{"count":0,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3394\/revisions"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=3394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=3394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=3394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}