{"id":3395,"date":"2012-05-30T12:37:01","date_gmt":"2012-05-30T10:37:01","guid":{"rendered":"http:\/\/www.grenzsteintrophy.de\/?p=3395"},"modified":"2012-12-15T21:54:09","modified_gmt":"2012-12-15T19:54:09","slug":"gst-interview-auf-zeit-de","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2012\/05\/gst-interview-auf-zeit-de\/","title":{"rendered":"GST-Interview auf Zeit.de"},"content":{"rendered":"<p>Die GST r&uuml;ckt n&auml;her, bei den Mitfahrern rauscht der Puls und im Bl&auml;tterwald rauscht es auch in Sachen GST. So kann man seit Sonntag auf Zeit.de ein Interview zur GST lesen. Hier der <a href=\"http:\/\/www.zeit.de\/auto\/2012-05\/grenzsteintrophy-fehlau\" target=\"_blank\">Link<\/a>!<\/p>","protected":false},"excerpt":{"rendered":"<p>Die GST r&uuml;ckt n&auml;her, bei den Mitfahrern rauscht der Puls und im Bl&auml;tterwald rauscht es auch in Sachen GST. So kann man seit Sonntag auf Zeit.de ein Interview zur GST lesen. Hier der Link!<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[61,95],"tags":[],"class_list":["post-3395","post","type-post","status-publish","format-standard","hentry","category-grenzsteintrophy","category-gst-media"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-SL","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=3395"}],"version-history":[{"count":0,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/3395\/revisions"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=3395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=3395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=3395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}