{"id":751,"date":"2009-06-28T22:17:01","date_gmt":"2009-06-28T21:17:01","guid":{"rendered":"http:\/\/www.grenzsteintrophy.de\/?p=751"},"modified":"2012-12-15T20:09:17","modified_gmt":"2012-12-15T18:09:17","slug":"pinguin-und-prinzknolf-2806","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2009\/06\/pinguin-und-prinzknolf-2806\/","title":{"rendered":"Pinguin und PrinzKnolf &#8211; 28.06. &#8211; 22:17"},"content":{"rendered":"<p>\u00dcbernommenes Posting aus dem <a href=\"http:\/\/eingangrad.de\/wbb\/thread.php?threadid=26462&amp;threadview=0&amp;hilight=&amp;hilightuser=0&amp;page=1\">Eingangradforum<\/a>:<\/p>\n<p>&#8220;Kurze Wasserstandsmeldung von PrinzKnolf und mir: Alles i.O., wir haben heute bei Duderstadt den Track Richtung Friedland und Kassel per Strasse verlassen und sind mit der Bahn gemeinsam bis W\u00dc gereist.<\/p>\n<p>Gesamtfahrleistung in ca. 100 Stunden zwischen Start am Strand und Bahnhof Kassel betrug etwas \u00fcber 750 km.<\/p>\n<p>Ich fange jetzt erst gar nicht an, zu lesen im &#8220;Thread&#8221;, ne Pizza steht da und ein Glas Wein.<\/p>\n<p>In diesem Sinne, guten Appetit und weiterhin viel Erfolg den Jungs auf der Strecke.&#8221;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00dcbernommenes Posting aus dem Eingangradforum: &#8220;Kurze Wasserstandsmeldung von PrinzKnolf und mir: Alles i.O., wir haben heute bei Duderstadt den Track Richtung Friedland und Kassel per Strasse verlassen und sind mit der Bahn gemeinsam bis W\u00dc&#8230; <\/p>\n<p class=\"more\"><a class=\"more-link\" href=\"https:\/\/grenzsteintrophy.de\/en\/2009\/06\/pinguin-und-prinzknolf-2806\/\">Read More<\/a><\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[61,83],"tags":[87],"class_list":["post-751","post","type-post","status-publish","format-standard","hentry","category-grenzsteintrophy","category-gst-doku","tag-gst-09"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-c7","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=751"}],"version-history":[{"count":0,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/751\/revisions"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}