{"id":9374,"date":"2016-05-09T08:43:07","date_gmt":"2016-05-09T06:43:07","guid":{"rendered":"http:\/\/overnighter.wp.velocontent.de\/?p=9374"},"modified":"2016-05-09T08:43:07","modified_gmt":"2016-05-09T06:43:07","slug":"gst-fahrer-2016-andreas-h","status":"publish","type":"post","link":"https:\/\/grenzsteintrophy.de\/en\/2016\/05\/gst-fahrer-2016-andreas-h\/","title":{"rendered":"GST-Fahrer 2016: Andreas H."},"content":{"rendered":"<div>Hallo GST,<\/div>\n<div>ich w\u00fcrde gerne 2016 dabei sein wollen,\u00a0f\u00fcr das komplette Abenteuer bis ans Meer wird es zeitlich zwar\u00a0nicht ganz klappen,\u00a0nichtsdestotrotz m\u00f6chte ich mit am Start stehen !<\/div>\n<div><\/div>\n<div>Mit sportlichen Gr\u00fc\u00dfen,<\/div>\n<div>Andreas H.<\/div>","protected":false},"excerpt":{"rendered":"<p>Hallo GST, ich w\u00fcrde gerne 2016 dabei sein wollen,\u00a0f\u00fcr das komplette Abenteuer bis ans Meer wird es zeitlich zwar\u00a0nicht ganz klappen,\u00a0nichtsdestotrotz m\u00f6chte ich mit am Start stehen ! Mit sportlichen Gr\u00fc\u00dfen, Andreas H.<\/p>\n","protected":false},"author":36,"featured_media":8777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[84],"tags":[],"class_list":["post-9374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gst-loi"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/grenzsteintrophy.de\/wp-content\/blogs.dir\/7\/files\/2015\/11\/gst16_Fahrer-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p8ekQv-2rc","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/9374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/comments?post=9374"}],"version-history":[{"count":1,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/9374\/revisions"}],"predecessor-version":[{"id":9376,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/posts\/9374\/revisions\/9376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media\/8777"}],"wp:attachment":[{"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/media?parent=9374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/categories?post=9374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grenzsteintrophy.de\/en\/wp-json\/wp\/v2\/tags?post=9374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}